{"id":240,"date":"2022-02-11T09:22:26","date_gmt":"2022-02-11T09:22:26","guid":{"rendered":"https:\/\/source.wpopal.com\/bookory\/?page_id=240"},"modified":"2026-03-02T22:26:38","modified_gmt":"2026-03-02T15:26:38","slug":"about-us","status":"publish","type":"page","link":"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/","title":{"rendered":"About Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"240\" class=\"elementor elementor-240\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-9f0e011 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f0e011\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a42040d\" data-id=\"a42040d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7379d19 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7379d19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 (7D Book)<\/h2>\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"elementor-element elementor-element-bf5d1ff elementor-widget elementor-widget-text-editor\" data-id=\"bf5d1ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h5>\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 (7D Book) \u201c\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e48\u0e21\u201d 7D : \u0e08\u0e34\u0e15\u0e27\u0e34\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e32<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ab83f1 elementor-widget elementor-widget-text-editor\" data-id=\"9ab83f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\u0e23\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e49\u0e32\u0e27\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e35 2019 \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e21\u0e35\u0e1d\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e22\u0e36\u0e14\u0e16\u0e37\u0e2d\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2b\u0e25\u0e31\u0e01 <strong>7Ds<\/strong>\u00a0\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\n<ul>\n \t<li><strong>Dignity<\/strong> (\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e28\u0e23\u0e35)<\/li>\n \t<li><strong>Devotion<\/strong> (\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e15\u0e19)<\/li>\n \t<li><strong>Difference<\/strong> (\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07)<\/li>\n \t<li><strong>Diversity<\/strong> (\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22)<\/li>\n \t<li><strong>Diligence<\/strong> (\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e30)<\/li>\n \t<li><strong>Dreamer<\/strong> (\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e1d\u0e31\u0e19)<\/li>\n \t<li><strong>Digital<\/strong> (\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25)<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48bb854 elementor-widget elementor-widget-text-editor\" data-id=\"48bb854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08<\/strong>\u00a0\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e21\u0e32\u0e01\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d \u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e25\u0e48\u0e21\u0e41\u0e25\u0e30 E-Book \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14\u201d \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e43\u0e19\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e13\u0e32\u0e18\u0e34\u0e01\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u00a0<strong>\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e35\u0e27\u0e34\u0e15\u00a0<\/strong>\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e01\u0e25\u0e38\u0e48\u0e21 Non-fiction \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07 (Self-improvement), \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 (Marketing &amp; Business) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e35\u0e27\u0e34\u0e15 (Life Management) \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e42\u0e14\u0e22\u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e21\u0e35\u00a0<strong>\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e1b\u0e25\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e25\u0e48\u0e21<\/strong>\u00a0\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e17\u0e22\u00a0<strong>\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u00a0<\/strong>\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e17\u0e38\u0e01\u0e40\u0e25\u0e48\u0e21\u0e04\u0e37\u0e2d \u201c\u0e04\u0e25\u0e37\u0e48\u0e19\u0e25\u0e39\u0e01\u0e40\u0e25\u0e47\u0e01\u201d \u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e04\u0e37\u0e19\u0e2a\u0e39\u0e48\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e40\u0e23\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e04\u0e19\u0e01\u0e49\u0e32\u0e27\u0e44\u0e1b\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e2a\u0e31\u0e48\u0e19\u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e1a\u0e27\u0e01\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e46 \u0e27\u0e31\u0e19<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11da14f elementor-widget elementor-widget-text-editor\" data-id=\"11da14f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h5><strong>\u0e27\u0e34\u0e2a\u0e31\u0e22\u0e17\u0e31\u0e28\u0e19\u0e4c (Vision)<\/strong><\/h5><p>\u201c\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e48\u0e21\u0e40\u0e1e\u0e32\u0e30\u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e01\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e49\u0e1e\u0e23\u0e21\u0e41\u0e14\u0e19\u201d<\/p><h5><strong>\u0e1e\u0e31\u0e19\u0e18\u0e01\u0e34\u0e08 (Mission)<\/strong><\/h5><p>1. Author Incubation &amp; Empowerment: \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e48\u0e21\u0e40\u0e1e\u0e32\u0e30\u0e41\u0e25\u0e30\u0e40\u0e08\u0e35\u0e22\u0e23\u0e30\u0e44\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e39\u0e41\u0e25\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e30<br \/>2. Curating Global Excellence: \u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e1b\u0e25\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e42\u0e25\u0e01 \u0e42\u0e14\u0e22\u0e40\u0e19\u0e49\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e01\u0e25<br \/>3. Global Rights &amp; Digital Distribution: \u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e15\u0e25\u0e32\u0e14\u0e42\u0e25\u0e01\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 Amazon \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e41\u0e25\u0e30\u0e02\u0e22\u0e32\u0e22\u0e10\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e01\u0e25<br \/>4. Social Progress Medium: \u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e41\u0e25\u0e30\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e49\u0e32\u0e27\u0e44\u0e1b\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae12b42 elementor-widget elementor-widget-image\" data-id=\"ae12b42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"400\" src=\"https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1.jpg\" class=\"attachment-full size-full wp-image-6743\" alt=\"\" srcset=\"https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1.jpg 960w, https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1-320x133.jpg 320w, https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1-400x167.jpg 400w, https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1-300x125.jpg 300w, https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1-768x320.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 (7D Book) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 (7D Book) \u201c\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e48\u0e21\u201d 7D : \u0e08\u0e34\u0e15\u0e27\u0e34\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e32 \u0e23\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e49\u0e32\u0e27\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e35 2019 \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e21\u0e35\u0e1d\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e22\u0e36\u0e14\u0e16\u0e37\u0e2d\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2b\u0e25\u0e31\u0e01 7Ds\u00a0\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32 Dignity (\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e28\u0e23\u0e35) Devotion (\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e15\u0e19) Difference (\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07) Diversity (\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22) Diligence (\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e30) Dreamer (\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e1d\u0e31\u0e19) Digital (\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25) \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u00a0\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e21\u0e32\u0e01\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d \u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e25\u0e48\u0e21\u0e41\u0e25\u0e30 E-Book \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14\u201d \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e43\u0e19\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e13\u0e32\u0e18\u0e34\u0e01\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u00a0\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e35\u0e27\u0e34\u0e15\u00a0\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e01\u0e25\u0e38\u0e48\u0e21 Non-fiction \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07 (Self-improvement), \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 (Marketing &amp; Business) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e35\u0e27\u0e34\u0e15 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-homepage.php","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-240","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About Us - 7D BOOK<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Us - 7D BOOK\" \/>\n<meta property=\"og:description\" content=\"\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 (7D Book) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 (7D Book) \u201c\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e48\u0e21\u201d 7D : \u0e08\u0e34\u0e15\u0e27\u0e34\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e32 \u0e23\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e49\u0e32\u0e27\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e35 2019 \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e21\u0e35\u0e1d\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e22\u0e36\u0e14\u0e16\u0e37\u0e2d\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2b\u0e25\u0e31\u0e01 7Ds\u00a0\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32 Dignity (\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e28\u0e23\u0e35) Devotion (\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e15\u0e19) Difference (\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07) Diversity (\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22) Diligence (\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e30) Dreamer (\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e1d\u0e31\u0e19) Digital (\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25) \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u00a0\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e21\u0e32\u0e01\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d \u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e25\u0e48\u0e21\u0e41\u0e25\u0e30 E-Book \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14\u201d \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e43\u0e19\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e13\u0e32\u0e18\u0e34\u0e01\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u00a0\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e35\u0e27\u0e34\u0e15\u00a0\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e01\u0e25\u0e38\u0e48\u0e21 Non-fiction \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07 (Self-improvement), \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 (Marketing &amp; Business) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e35\u0e27\u0e34\u0e15 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"7D BOOK\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T15:26:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/index.php\\\/about-us\\\/\",\"url\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/index.php\\\/about-us\\\/\",\"name\":\"About Us - 7D BOOK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/index.php\\\/about-us\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/index.php\\\/about-us\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/bg_store1.jpg\",\"datePublished\":\"2022-02-11T09:22:26+00:00\",\"dateModified\":\"2026-03-02T15:26:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/index.php\\\/about-us\\\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/somjate.jwtcdev.com\\\/index.php\\\/about-us\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/index.php\\\/about-us\\\/#primaryimage\",\"url\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/bg_store1.jpg\",\"contentUrl\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/bg_store1.jpg\",\"width\":960,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/index.php\\\/about-us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/#website\",\"url\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/\",\"name\":\"7D BOOK\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/#organization\",\"name\":\"7D BOOK\",\"url\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-7d_logo-300x200-1.png\",\"contentUrl\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-7d_logo-300x200-1.png\",\"width\":300,\"height\":200,\"caption\":\"7D BOOK\"},\"image\":{\"@id\":\"https:\\\/\\\/somjate.jwtcdev.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Us - 7D BOOK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/","og_locale":"en_US","og_type":"article","og_title":"About Us - 7D BOOK","og_description":"\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 (7D Book) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 (7D Book) \u201c\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e48\u0e21\u201d 7D : \u0e08\u0e34\u0e15\u0e27\u0e34\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e32 \u0e23\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e49\u0e32\u0e27\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e35 2019 \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e21\u0e35\u0e1d\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e22\u0e36\u0e14\u0e16\u0e37\u0e2d\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2b\u0e25\u0e31\u0e01 7Ds\u00a0\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32 Dignity (\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e28\u0e23\u0e35) Devotion (\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e15\u0e19) Difference (\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07) Diversity (\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22) Diligence (\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e30) Dreamer (\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e1d\u0e31\u0e19) Digital (\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25) \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u00a0\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19\u0e14\u0e35 \u0e1a\u0e38\u0e4a\u0e04 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e21\u0e32\u0e01\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d \u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e25\u0e48\u0e21\u0e41\u0e25\u0e30 E-Book \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14\u201d \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e43\u0e19\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e13\u0e32\u0e18\u0e34\u0e01\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u00a0\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e35\u0e27\u0e34\u0e15\u00a0\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e01\u0e25\u0e38\u0e48\u0e21 Non-fiction \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07 (Self-improvement), \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 (Marketing &amp; Business) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e35\u0e27\u0e34\u0e15 [&hellip;]","og_url":"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/","og_site_name":"7D BOOK","article_modified_time":"2026-03-02T15:26:38+00:00","og_image":[{"width":960,"height":400,"url":"https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/","url":"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/","name":"About Us - 7D BOOK","isPartOf":{"@id":"https:\/\/somjate.jwtcdev.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/#primaryimage"},"image":{"@id":"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/#primaryimage"},"thumbnailUrl":"https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1.jpg","datePublished":"2022-02-11T09:22:26+00:00","dateModified":"2026-03-02T15:26:38+00:00","breadcrumb":{"@id":"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/#primaryimage","url":"https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1.jpg","contentUrl":"https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2022\/11\/bg_store1.jpg","width":960,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/somjate.jwtcdev.com\/index.php\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/somjate.jwtcdev.com\/"},{"@type":"ListItem","position":2,"name":"About Us"}]},{"@type":"WebSite","@id":"https:\/\/somjate.jwtcdev.com\/#website","url":"https:\/\/somjate.jwtcdev.com\/","name":"7D BOOK","description":"","publisher":{"@id":"https:\/\/somjate.jwtcdev.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/somjate.jwtcdev.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/somjate.jwtcdev.com\/#organization","name":"7D BOOK","url":"https:\/\/somjate.jwtcdev.com\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/somjate.jwtcdev.com\/#\/schema\/logo\/image\/","url":"https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2026\/03\/cropped-7d_logo-300x200-1.png","contentUrl":"https:\/\/somjate.jwtcdev.com\/wp-content\/uploads\/2026\/03\/cropped-7d_logo-300x200-1.png","width":300,"height":200,"caption":"7D BOOK"},"image":{"@id":"https:\/\/somjate.jwtcdev.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/somjate.jwtcdev.com\/index.php\/wp-json\/wp\/v2\/pages\/240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somjate.jwtcdev.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/somjate.jwtcdev.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/somjate.jwtcdev.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/somjate.jwtcdev.com\/index.php\/wp-json\/wp\/v2\/comments?post=240"}],"version-history":[{"count":22,"href":"https:\/\/somjate.jwtcdev.com\/index.php\/wp-json\/wp\/v2\/pages\/240\/revisions"}],"predecessor-version":[{"id":9662,"href":"https:\/\/somjate.jwtcdev.com\/index.php\/wp-json\/wp\/v2\/pages\/240\/revisions\/9662"}],"wp:attachment":[{"href":"https:\/\/somjate.jwtcdev.com\/index.php\/wp-json\/wp\/v2\/media?parent=240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}